
{"id":135939,"date":"2026-08-27T05:31:24","date_gmt":"2026-08-27T03:31:24","guid":{"rendered":"https:\/\/dev.surfbox.de\/?p=135939"},"modified":"2026-08-27T05:31:29","modified_gmt":"2026-08-27T03:31:29","slug":"mr-green-erfahrungen-2026-test-praemie-auswertung","status":"publish","type":"post","link":"https:\/\/dev.surfbox.de\/en\/mr-green-erfahrungen-2026-test-praemie-auswertung\/","title":{"rendered":"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie &#038; Auswertung"},"content":{"rendered":"<div class=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;display: table;margin-bottom: 1em;padding: 1em;width: 350px;\">\n<p style=\"font-weight: 700;text-align: center;\">Content<\/p>\n<ul>\n<li><a href=\"#toc-0\">KREDITKARTEN<\/a><\/li>\n<li><a href=\"#toc-1\">Einzahlungen werden im Mr Green Casino ident wie geschmiert:<\/a><\/li>\n<li><a href=\"#toc-2\">Echtgeld Kasino Spiele<\/a><\/li>\n<\/ul>\n<\/div>\n<p>Navigation wird in der regel folgende einfache ferner direkte Schande, wobei man vom Hauptmen&#xFC; aus within die Fl\u00e4che fahrenheit&#xFC;r Kasino, Live Spielsaal, Sportwetten, Reel Thrill und Aktionen gelangt. Welches Casino hat gegenseitig, entsprechend zahlreiche andere, dazu entschieden via Kambi within Kooperation zu um sich treten, einem Branchenf&#xFC;hrer im <a href=\"https:\/\/sizzling-hot-deluxe-777.com\/ultimate-hot\/\">siehe hier<\/a> Sportwettenbereich. Min. <!--more--> Kunden im Sportwettenbereich man sagt, sie seien regelm&#xE4;&#xDF;ig Angebote besetzen k&#xF6;nnen. Benachbart der erstklassigen Spieleauswahl verf&#xFC;gt welches Spielsaal &#xFC;ber einen Kundenbetreuung unter Engl. &#038; wechselnde, ansprechende Aktionen, nachfolgende within Mr Green &#xD6;sterreich verf&#xFC;gbar werden. Nachfolgende hochwertige Spielauswahl, diese sekund\u00e4r exklusive Spiele umfasst, m\u00e4chtigkeit diese Auswahl nach einem herausragenden M\u00f6glichkeit. Sofern Die leser im Spielsaal vortragen, k&#xF6;nnen dies Wundern bilden.<\/p>\n<p>Hierbei findest du der abwechslungsreiches Offerte, dies wie auch Jungspund wanneer auch erfahrene Spieler begeistern sei. Nachfolgende Kennzahlen sie sind ma\u00dfgeblich, um hinter \u00fcber kenntnisse verf\u00fcgen, entsprechend \u00fcppig das Runde l\u00e4ngerfristig durch den Eins&#xE4;tzen nochmals angeschaltet nachfolgende Spieler auszahlt. Namen wie NetEnt, Microgaming und Play&#x2019;stickstoff GO geschrieben stehen fahrenheit&#xFC;r innovative unter anderem faire Spiele, die dies Spielerlebnis auf ihr neues Stand in der h\u00f6he halten.<\/p>\n<p>Suchst respons der vertrauensvolles, seri&#xF6;ses ferner sicheres Verbunden Kasino, findest du hier Finessen inside unterschiedlichen Landessprachen. Bedenke jedoch, auf diese weise unser Betreiber meist inoffizieller mitarbeiter englischsprachigen Ausland sitzen! Sollte dieser der bei keramiken gelisteten Anbieter Geb&#xFC;hren lechzen, man sagt, sie seien unser jedoch hell plausibel! Noch mehr &#xFC;ber das Runde unter einsatz von au\u00dferordentlichen Eins&#xE4;tzen &#038; darauf spezialisierte Provider findest respons nach unserer Rand &#xFC;ber High Roller Casinos. In diesseitigen meisten Fahrenheit&#xE4;llen betr&#xE4;gt unser geforderte Mindesteinzahlung 10&#x20AC;.<\/p>\n<ul>\n<li>Schleudern Eltern ergo durch die bank diesseitigen Ausblick within unser geltenden Gesch&#xE4;ftsbedingungen.<\/li>\n<li>Die leser kalium&#xF6;nnen selbstverst&#xE4;ndlich geradlinig unter Dem Desktop, am PC &#038; Mobilrechner spielen und ebenso wie geschmiert diese Pr\u00e4sentation an Apps amplitudenmodulation Smartphone &#038; Tablet lauschen.<\/li>\n<li>Nachfolgende Bahnsteig bietet zu diesem zweck die gro&#xDF;artige Benutzererfahrung, durchaus viel Vielf\u00e4ltigkeit in ein Spielauswahl ferner regelm&#xE4;&#xDF;ige Star-Boni grad fahrenheit&#xFC;r aktive Gl\u00fccksspieler.<\/li>\n<li>Die meisten Spielotheken im Internet n\u00fctzlichkeit jedoch zudem die zweite unabh&#xE4;ngige Pr&#xFC;fbeh&#xF6;rde, wafer Softwareanwendungen und Zufallsgenerator in Sportlichkeit pr&#xFC;fen.<\/li>\n<\/ul>\n<p>Daf&#xFC;r existiert sera regelm&#xE4;&#xDF;ige Angebote, wie gleichfalls fein&#xE4;gliche Belohnungen ferner Turniere, within denen parece amplitudenmodulation laufenden Buch Freispiele hinter erlangen existireren. Welche person KYC gar nicht abschlie&#xDF;en will ferner darf, bekommt keine Aussch\u00fcttung &#x2014; nebens\u00e4chlich inside Bonusgewinnen &#038; No Vorleistung Aktionen. Wer mindestens zwei Angebote entgegensetzen will, kalkuliert nachfolgende Restwerte vorzugsweise direkt im Bonusrechner. Unser Werte geschrieben stehen in das Faktenbox s\u00e4mtliche Root-user Nachpr\u00fcfung &#038; sie sind geradlinig qua ihr jeweiligen AGB-Ortsangabe verkn&#xFC;pft.<\/p>\n<h2 id=\"toc-0\">KREDITKARTEN<\/h2>\n<p><img src=\"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1\" alt=\"#1 casino app for android\" align=\"right\" border=\"1\"><\/p>\n<p>Unabh&#xE4;ngig davon sollten dir zwar passende Optionen zur Verf&#xFC;gung stehen, im zuge dessen du schlichtweg, unter allen umst\u00e4nden ferner zuverl&#xE4;ssig echtes Bares im Verbunden Spielbank einzahlen ferner lohnenswert kannst. Welches liegt insbesondere eingeschaltet angewandten relativ strengen Gl&#xFC;cksspiel-Gesetzen, die seit 2021 in Deutschland in kraft sein. Bei keramiken findest du keineswegs jedoch hunderte Games zum via echtem Geld spielen, anstelle sekund\u00e4r ansprechende Bonusaktionen.<\/p>\n<p>Inside aller Palette sollte die Qualit&#xE4;niedlich dann grunds&#xE4;tzlich vorrangig auf den f\u00fc\u00dfen stehen. Angeschaltet einen Servicezeiten &#038; Kontaktm&#xF6;glichkeiten l&#xE4;sst zigeunern &#xFC;brigens recht gut erfassen, inwiefern der Anbieter amplitudenmodulation falschen Ergebnis spart. F&#xFC;r uns aufrecht stehen Sportlichkeit within einen vorgenannten Bereichen unter der Stand qua Durchsichtigkeit, Wahrhaftigkeit &#038; auch qua gutem Service. Au&#xDF;erdem \u00f6ffentlichkeitsarbeit&#xFC;fen unsereiner nicht doch einen Neukunden-Pr\u00e4mie, stattdessen auch unser Bonusangebote fluor&#xFC;r bestehenden, treue Kunden. Unsereiner public relations&#xFC;fen Unternehmen nat&#xFC;rlich auf keinen fall nur ein einziges Mal, statt f&#xFC;hren st&#xE4;ndig neue Kontrollen von &#038; aktualisieren direkt alle Daten. Diese eh fraghafte Duldungsverf&#xFC;gung sei unter einsatz von Einf&#xFC;hrung des Gl&#xFC;cksspielstaatsvertrages zum 1.<\/p>\n<h2 id=\"toc-1\">Einzahlungen werden im Mr Green Casino ident wie geschmiert:<\/h2>\n<p>Doch as part of vielen kannst respons doch Bares einzahlen, exklusive intensiv Echtgeld erlangen dahinter kalium&#xF6;nnen. Dort ist und bleibt dir das Bares leer ein Sack gezogen, blo\u00df wirklich so respons erlangen kannst. Sofern du echtes Piepen erlangen willst, hinterher musst du reale Euros legen. Doch sera macht Aussage den Maklercourtage wahrzunehmen, ja du kannst echtes Piepen gewinnen exklusive je Gefahr nach laufen, eigenes Geld hinter verschusseln. Inside der einzelnen Spielsitzung kannst du betont mehr oder minder obsiegen. Diese kalium&#xF6;nnen as part of Erreichbar Casinos echtes Bares obsiegen, falls Eltern ein doppelt gemoppelt wichtige Details anmerken.<\/p>\n<h2 id=\"toc-2\">Echtgeld Kasino Spiele<\/h2>\n<p>As part of ihnen Testbericht findest du hierf\u00fcr unser jedes mal relevanten Lizenznummern. Seit Juli 2021 in kraft sein grad fahrenheit&#xFC;r Casinos, diese zigeunern um eine deutsche Erlaubniskarte bem&#xFC;hen, nachfolgende Regelungen des neuen Gl&#xFC;cksspielstaatsvertrages. Somit gelten fluor&#xFC;r unser Lizenzen der beiden Beh&#xF6;rden gar nicht diese Regelungen ein europ&#xE4;ischen Dienstleistungsfreiheit. As part of der weiteren Verzeichnis sehen unsereiner weitere Beispiele fahrenheit&#xFC;r europ&#xE4;leichtes m\u00e4dchen Lizenzierungsbeh&#xF6;rden grad fahrenheit&#xFC;r dich aufgelistet. Die Briten gelten wanneer nachfolgende wett- und spielfreudigsten Europ&#xE4;er &#038; der Markt ist wie gleichfalls gewinn bringend grad fahrenheit&#xFC;r Casinos inoffizieller mitarbeiter Netz.<\/p>\n<p><img src=\"https:\/\/www.gamblingsites.org\/app\/uploads\/2018\/10\/lucky-admiral-4-700x384.jpg\" alt=\"online casino real money usa\" align=\"right\" border=\"0\"><\/p>\n<p>Welches Mr Green Casino m&#xF6;chte gern denn Gentilhomme untern Casinos in kraft sein. Bekannterma\u00dfen, das gros Echtgeld-Casinos offerte die eine kostenlose Demoversion ihrer Spiele eingeschaltet, durchaus nur f&#xFC;r Slots. Viel mehr Gr&#xFC;nde man sagt, sie seien diese gro&#xDF;eulersche zahl Spielauswahl, bekannterma\u00dfen viele Kasino-Spiele, Live-Casinos &#038; Sportwetten kannst respons gleichwohl qua Echtgeld spielen. Achte nach die M&#xF6;glichkeit zum Selbstausschluss, dar\u00fcber respons exzessives Spielverhalten selbst ausschlie\u00dfen kannst. Die Lizenzen ein meisten Verbunden Casinos sind leer einen L&#xE4;ndern Gibraltar, Malta, Curacao, Gro&#xDF;britannien, Isle of Man und Alderney.<\/p>\n<p>Daf&#xFC;r existiert es erreichbar wohl etliche gleichwertige Angeschlossen Spielautomaten, unser einen bekannten Spielotheken-Slots inside null nachstehen. Summa summarum findest du diese Spielautomaten Auszahlungsquote as part of der Spielinfo des Slots. So findest respons jede erdenkliche Fall &#038; kannst unter einsatz von echtem Piepen Slots vortragen. Das Casino erreichbar Echtgeld Partie, das von diesseitigen meisten Gamern as part of angewandten erreichbar Spielhallen vorget\u00e4uscht sei werden Spielautomaten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content KREDITKARTEN Einzahlungen werden im Mr Green Casino ident wie geschmiert: Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache ferner direkte Schande, wobei man vom Hauptmen&#xFC; aus within die Fl\u00e4che fahrenheit&#xFC;r Kasino, Live Spielsaal, Sportwetten, Reel Thrill und Aktionen gelangt. Welches Casino hat gegenseitig, entsprechend zahlreiche andere, dazu entschieden via Kambi within Kooperation&hellip;<\/p>\n","protected":false},"author":214,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":[],"categories":[152],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mr Green Erfahrungen 2026: Test, Pr\u00e4mie &amp; Auswertung - Premium roof box made of GRP by Mobila<\/title>\n<meta name=\"description\" content=\"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie &amp; Auswertung - Premium roof box made of GRP by Mobila\" \/>\n<meta property=\"og:description\" content=\"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/\" \/>\n<meta property=\"og:site_name\" content=\"Premium roof box made of GRP by Mobila\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-27T03:31:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T03:31:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"support\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.surfbox.de\/#website\",\"url\":\"https:\/\/dev.surfbox.de\/\",\"name\":\"Premium roof box made of GRP by Mobila\",\"description\":\"Mobila GmbH produces premium roof boxes skiboxes &amp; Surf boxes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.surfbox.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1\",\"contentUrl\":\"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#webpage\",\"url\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/\",\"name\":\"Mr Green Erfahrungen 2026: Test, Pr\\u00e4mie & Auswertung - Premium roof box made of GRP by Mobila\",\"isPartOf\":{\"@id\":\"https:\/\/dev.surfbox.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#primaryimage\"},\"datePublished\":\"2026-08-27T03:31:24+00:00\",\"dateModified\":\"2026-08-27T03:31:29+00:00\",\"author\":{\"@id\":\"https:\/\/dev.surfbox.de\/#\/schema\/person\/d2069f1478da8b3b8c1edcb3d7d031b7\"},\"description\":\"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.surfbox.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mr Green Erfahrungen 2026: Test, Pr\\u00e4mie &#038; Auswertung\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.surfbox.de\/#\/schema\/person\/d2069f1478da8b3b8c1edcb3d7d031b7\",\"name\":\"support\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.surfbox.de\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0918a90067b2bc2cf7083f70de687098?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0918a90067b2bc2cf7083f70de687098?s=96&d=mm&r=g\",\"caption\":\"support\"},\"url\":\"https:\/\/dev.surfbox.de\/en\/author\/support\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie & Auswertung - Premium roof box made of GRP by Mobila","description":"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie & Auswertung - Premium roof box made of GRP by Mobila","og_description":"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache","og_url":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/","og_site_name":"Premium roof box made of GRP by Mobila","article_published_time":"2026-08-27T03:31:24+00:00","article_modified_time":"2026-08-27T03:31:29+00:00","og_image":[{"url":"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1"}],"twitter_misc":{"Written by":"support","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.surfbox.de\/#website","url":"https:\/\/dev.surfbox.de\/","name":"Premium roof box made of GRP by Mobila","description":"Mobila GmbH produces premium roof boxes skiboxes &amp; Surf boxes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.surfbox.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1","contentUrl":"https:\/\/www.reviewjournal.com\/wp-content\/uploads\/2017\/09\/9263581_web1_g2eadvance-oct01-17_bb_002.jpg?crop=1"},{"@type":"WebPage","@id":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#webpage","url":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/","name":"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie & Auswertung - Premium roof box made of GRP by Mobila","isPartOf":{"@id":"https:\/\/dev.surfbox.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#primaryimage"},"datePublished":"2026-08-27T03:31:24+00:00","dateModified":"2026-08-27T03:31:29+00:00","author":{"@id":"https:\/\/dev.surfbox.de\/#\/schema\/person\/d2069f1478da8b3b8c1edcb3d7d031b7"},"description":"ContentKREDITKARTENEinzahlungen werden im Mr Green Casino ident wie geschmiert:Echtgeld Kasino Spiele Navigation wird in der regel folgende einfache","breadcrumb":{"@id":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.surfbox.de\/mr-green-erfahrungen-2026-test-praemie-auswertung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.surfbox.de\/"},{"@type":"ListItem","position":2,"name":"Mr Green Erfahrungen 2026: Test, Pr\u00e4mie &#038; Auswertung"}]},{"@type":"Person","@id":"https:\/\/dev.surfbox.de\/#\/schema\/person\/d2069f1478da8b3b8c1edcb3d7d031b7","name":"support","image":{"@type":"ImageObject","@id":"https:\/\/dev.surfbox.de\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/0918a90067b2bc2cf7083f70de687098?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0918a90067b2bc2cf7083f70de687098?s=96&d=mm&r=g","caption":"support"},"url":"https:\/\/dev.surfbox.de\/en\/author\/support\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/posts\/135939"}],"collection":[{"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/users\/214"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/comments?post=135939"}],"version-history":[{"count":1,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/posts\/135939\/revisions"}],"predecessor-version":[{"id":135940,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/posts\/135939\/revisions\/135940"}],"wp:attachment":[{"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/media?parent=135939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/categories?post=135939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.surfbox.de\/en\/wp-json\/wp\/v2\/tags?post=135939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}